{"id":2369,"date":"2025-04-02T20:36:00","date_gmt":"2025-04-02T14:06:00","guid":{"rendered":"https:\/\/ambyangon.esteri.it\/?p=2369"},"modified":"2025-04-02T20:36:00","modified_gmt":"2025-04-02T14:06:00","slug":"terremoto-in-myanmar-deliberati-contributi-di-emergenza-della-cooperazione-italiana","status":"publish","type":"post","link":"https:\/\/ambyangon.esteri.it\/it\/news\/dall_ambasciata\/2025\/04\/terremoto-in-myanmar-deliberati-contributi-di-emergenza-della-cooperazione-italiana\/","title":{"rendered":"Terremoto in Myanmar. Deliberati contributi di emergenza della Cooperazione Italiana"},"content":{"rendered":"<div class=\"entry-content\">\n<p>In risposta alle gravi conseguenze del violento terremoto che lo scorso 28 marzo ha colpito il Myanmar, l\u2019Italia ha da subito messo in campo le proprie eccellenze per fornire un primo supporto concreto alle popolazioni interessate in questo momento di particolare criticit\u00e0.<\/p>\n<p>Il Vice Ministro Cirielli ha infatti deliberato un contributo di emergenza di 2 milioni di Euro a favore della Federazione Internazionale delle societ\u00e0 di Croce Rossa e Mezzaluna Rossa (FICROSS), prontamente disposto attraverso la Cooperazione Italiana per la fornitura di aiuti immediati e assistenza alle comunit\u00e0 pi\u00f9 colpite dal terremoto. \u00c8 inoltre prossimo alla pubblicazione un bando di emergenza da ulteriori 1.3 milioni, che si focalizzer\u00e0 sulla risposta alla crisi e che coinvolger\u00e0 le numerose Organizzazioni della Societ\u00e0 Civile italiane gi\u00e0 presenti nel Paese e che, sin dalle prime ore successive all\u2019evento, si sono mobilitate con tempestivit\u00e0 ed efficacia per prestare assistenza alle vittime.<\/p>\n<p>Parallelamente, la Cooperazione Italiana continua il coordinamento con tutti gli attori coinvolti, soprattutto attraverso la Protezione Civile e l\u2019apposito Meccanismo dell\u2019Unione Europea, al fine di organizzare un\u2019operazione di trasporto umanitario destinata alla fornitura di beni di prima necessit\u00e0 in risposta ai bisogni urgenti rilevati sul terreno.<\/p>\n<p>Oltre ad affrontare l\u2019emergenza nell\u2019immediato, l\u2019impegno dell\u2019Italia mira a coordinare interventi di diversa natura a sostegno delle comunit\u00e0 colpite.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"In risposta alle gravi conseguenze del violento terremoto che lo scorso 28 marzo ha colpito il Myanmar, l\u2019Italia ha da subito messo in campo le proprie eccellenze per fornire un primo supporto concreto alle popolazioni interessate in questo momento di particolare criticit\u00e0. Il Vice Ministro Cirielli ha infatti deliberato un contributo di emergenza di 2 [&hellip;]","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-2369","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/ambyangon.esteri.it\/it\/wp-json\/wp\/v2\/posts\/2369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambyangon.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ambyangon.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ambyangon.esteri.it\/it\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/ambyangon.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=2369"}],"version-history":[{"count":1,"href":"https:\/\/ambyangon.esteri.it\/it\/wp-json\/wp\/v2\/posts\/2369\/revisions"}],"predecessor-version":[{"id":2371,"href":"https:\/\/ambyangon.esteri.it\/it\/wp-json\/wp\/v2\/posts\/2369\/revisions\/2371"}],"wp:attachment":[{"href":"https:\/\/ambyangon.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=2369"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ambyangon.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=2369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}